{"id":17406,"date":"2019-07-28T18:09:02","date_gmt":"2019-07-28T16:09:02","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=17406"},"modified":"2020-01-20T11:16:34","modified_gmt":"2020-01-20T10:16:34","slug":"f_33","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-f\/f_33\/","title":{"rendered":"FANTON Joseph (1823\u20131909)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>Joseph FANTON<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1823 \u2013 1909<\/strong><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-4276.jpg\" alt=\"\" data-source-id=\"i.0\" data-asset-id=\"17405\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on <\/strong>et<strong> cultivateur<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Colombeix (Saint-Amand-Jartoudeix)<\/p>\n<p style=\"text-align: center;\">le 2 janvier 1823<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">L\u00e9onard FANTON \/ Jeanne RAPAUD<\/p>\n<p style=\"text-align: center;\">cultivateurs<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1844<\/strong><em><strong>,<\/strong> Joseph habite Saint-Pardoux-Lavaud avec ses parents. Il est dispens\u00e9 de service militaire ayant un fr\u00e8re sous les drapeaux.<\/em><\/p>\n<p><em> Il \u00e9pouse Marie <\/em><strong>GUYOT<\/strong><em> le 19 f\u00e9vrier <\/em><strong>1849<\/strong><em> \u00e0 Saint-Pierre-le-Bost (contrat Lepetit au Monteil-au-Vicomte).<\/em><\/p>\n<p><em> Ils habitent Saint-Pardoux, puis Lascaux, commune de Banize.<\/em><\/p>\n<p><em>Ils d\u00e9c\u00e8dent \u00e0 Lascaux\u00a0:<\/em><\/p>\n<ul>\n<li><em>Marie, le 16 ao\u00fbt <\/em><strong>1904<\/strong><em>, \u00e2g\u00e9e de 74 ans<\/em><\/li>\n<li><em>Joseph, le 4 novembre <\/em><strong>1909<\/strong><em>, \u00e2g\u00e9 de 86 ans<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026Joseph FANTON 1823 \u2013 1909 ma\u00e7on et cultivateur n\u00e9 \u00e0 Colombeix (Saint-Amand-Jartoudeix) le 2 janvier 1823 fils de L\u00e9onard FANTON \/ Jeanne RAPAUD cultivateurs \u25d9 En 1844, Joseph habite Saint-Pardoux-Lavaud avec ses parents. Il est dispens\u00e9 de service militaire ayant un fr\u00e8re sous les drapeaux. Il \u00e9pouse Marie GUYOT le ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-f\/f_33\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-17406","post","type-post","status-publish","format-standard","hentry","category-lettre-f"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/17406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=17406"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/17406\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=17406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=17406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=17406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}