{"id":31657,"date":"2019-07-29T22:10:04","date_gmt":"2019-07-29T20:10:04","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=31657"},"modified":"2022-03-11T16:31:48","modified_gmt":"2022-03-11T15:31:48","slug":"b_717","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_717\/","title":{"rendered":"BOUNICHON L\u00e9onard (1844\u2013apr\u00e8s 1871)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>L\u00e9onard BOUNICHON<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1844 \u2013 apr\u00e8s 1871<\/strong><\/p>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/BOUNICHON-Leonard-1844-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-195809 aligncenter\" src=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/BOUNICHON-Leonard-1844--300x61.jpg\" alt=\"\" width=\"300\" height=\"61\" srcset=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/BOUNICHON-Leonard-1844--300x61.jpg 300w, https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/BOUNICHON-Leonard-1844--16x3.jpg 16w, https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/BOUNICHON-Leonard-1844--150x31.jpg 150w, https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/BOUNICHON-Leonard-1844-.jpg 442w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 au bourg de Saint-Martin-Ch\u00e2teau<\/p>\n<p style=\"text-align: center;\">le 16 octobre 1844<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">L\u00e9onard BOUNICHON, <span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">Jeanne POURRADE, cultivatrice<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1865<\/strong><em>, L\u00e9onard travaille dans le <\/em><span style=\"color: #0000ff;\"><strong>Rh\u00f4ne (69)<\/strong><\/span><em> et y passe le conseil de r\u00e9vision.<\/em><\/p>\n<p><strong>En 1871<\/strong><em>, il travaille \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Aubagne (13)<\/strong><\/span><em>.<\/em><\/p>\n<p>Il y \u00e9pouse, le 4 septembre de la m\u00eame ann\u00e9e, Marie Colombe <strong>PAGANELLI<\/strong>, tailleuse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026L\u00e9onard BOUNICHON 1844 \u2013 apr\u00e8s 1871 ma\u00e7on n\u00e9 au bourg de Saint-Martin-Ch\u00e2teau le 16 octobre 1844 fils de L\u00e9onard BOUNICHON, ma\u00e7on Jeanne POURRADE, cultivatrice \u25d9 En 1865, L\u00e9onard travaille dans le Rh\u00f4ne (69) et y passe le conseil de r\u00e9vision. En 1871, il travaille \u00e0 Aubagne (13). Il y \u00e9pouse, ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_717\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-31657","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=31657"}],"version-history":[{"count":3,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31657\/revisions"}],"predecessor-version":[{"id":195810,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31657\/revisions\/195810"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=31657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=31657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=31657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}