{"id":31710,"date":"2019-07-29T22:10:00","date_gmt":"2019-07-29T20:10:00","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=31710"},"modified":"2023-01-04T13:54:32","modified_gmt":"2023-01-04T12:54:32","slug":"b_709","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_709\/","title":{"rendered":"BOUNICHON L\u00e9onard (vers 1691\u2013entre 1740 et 1760)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>L\u00e9onard BOUNICHON<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>vers 1691 \u2013 entre 1740 et 1760<\/strong><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-7727.jpg\" alt=\"\" data-asset-id=\"31707\" data-source-id=\"i.0\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on <\/strong><\/span>et <span style=\"color: #008000;\"><strong>cultivateur<\/strong><\/span><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Saint-Martin-Ch\u00e2teau\u00a0?<\/p>\n<p style=\"text-align: center;\">vers 1691<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">L\u00e9onard BOUNICHON, <em>\u25ba<\/em> <a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/08\/MARGUILLIER.png\" target=\"_blank\" rel=\"noopener noreferrer\">marguillier<\/a> \/ L\u00e9onarde PR\u00c9VOST<\/p>\n<p style=\"text-align: center;\">laboureurs<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><em> L\u00e9onard \u00e9pouse Jeanne <\/em><strong>PITANCE<\/strong><em> le 15 f\u00e9vrier <\/em><strong>1706<\/strong><em> \u00e0 Saint-Martin (contrat Mian \u00e0 Peyrat-le-Ch\u00e2teau \u2013 87).<\/em><\/p>\n<p><em> Ils habitent le bourg de Saint-Martin.<\/em><\/p>\n<p>S17<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026L\u00e9onard BOUNICHON vers 1691 \u2013 entre 1740 et 1760 ma\u00e7on et cultivateur &nbsp; n\u00e9 \u00e0 Saint-Martin-Ch\u00e2teau\u00a0? vers 1691 fils de L\u00e9onard BOUNICHON, \u25ba marguillier \/ L\u00e9onarde PR\u00c9VOST laboureurs \u25d9 L\u00e9onard \u00e9pouse Jeanne PITANCE le 15 f\u00e9vrier 1706 \u00e0 Saint-Martin (contrat Mian \u00e0 Peyrat-le-Ch\u00e2teau \u2013 87). Ils habitent le bourg de ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_709\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-31710","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=31710"}],"version-history":[{"count":1,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31710\/revisions"}],"predecessor-version":[{"id":203817,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31710\/revisions\/203817"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=31710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=31710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=31710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}