{"id":31758,"date":"2019-07-29T22:09:59","date_gmt":"2019-07-29T20:09:59","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=31758"},"modified":"2020-01-20T11:11:06","modified_gmt":"2020-01-20T10:11:06","slug":"b_644","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_644\/","title":{"rendered":"BON Jean (1889\u20131975)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>Jean BON<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1889 \u2013 1975<\/strong><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-7730.jpg\" alt=\"\" data-asset-id=\"31755\" data-source-id=\"i.0\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 La Vedrenne (Saint-Moreil)<\/p>\n<p style=\"text-align: center;\">le 22 mars 1889<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Pierre BON \/ Marie CLAVAUD<\/p>\n<p style=\"text-align: center;\">cultivateurs<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1910<\/strong><em>, Jean travaille dans le <\/em><span style=\"color: #0000ff;\"><strong>Rh\u00f4ne (69)<\/strong><\/span><em> et doit y passer le conseil de r\u00e9vision.<\/em><\/p>\n<p><em> Il \u00e9pouse Marie-Th\u00e9r\u00e8se <\/em><strong>P\u00c9NY<\/strong><em> le 21 f\u00e9vrier <\/em><strong>1914<\/strong><em> \u00e0 Saint-Moreil (contrat Vergnaud \u00e0 Peyrat-le-Ch\u00e2teau \u2013 87). Ils habitent La Vedrenne.<\/em><\/p>\n<p><strong>En 1918<\/strong><em>, Jean est mobilis\u00e9 au 52e r\u00e9giment d\u2019artillerie.<\/em><\/p>\n<p><em>Marie-Th\u00e9r\u00e8se d\u00e9c\u00e8de au bourg de Saint-Moreil le 26 octobre de la m\u00eame ann\u00e9e, \u00e2g\u00e9e de 25 ans.<\/em><\/p>\n<p><em> Jean se remarie \u00e0 Saint-Moreil le 23 d\u00e9cembre <\/em><strong>1929<\/strong><em> avec Marie Delphine <\/em><strong>DUMAS <\/strong><em>(contrat Vergnaud \u00e0 Peyrat-le-Ch\u00e2teau \u2013 87).<\/em><\/p>\n<p><em>Ils d\u00e9c\u00e8dent\u00a0:<\/em><\/p>\n<ul>\n<li><em>Jean, \u00e0 La Vedrenne le 15 ao\u00fbt <\/em><strong>1975<\/strong><em>, \u00e2g\u00e9 de 86 ans<\/em><\/li>\n<li><em>Delphine, \u00e0 Cheissoux (87) le 25 d\u00e9cembre <\/em><strong>1980<\/strong><em>, \u00e2g\u00e9e de 85 ans<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026Jean BON 1889 \u2013 1975 ma\u00e7on n\u00e9 \u00e0 La Vedrenne (Saint-Moreil) le 22 mars 1889 fils de Pierre BON \/ Marie CLAVAUD cultivateurs \u25d9 En 1910, Jean travaille dans le Rh\u00f4ne (69) et doit y passer le conseil de r\u00e9vision. Il \u00e9pouse Marie-Th\u00e9r\u00e8se P\u00c9NY le 21 f\u00e9vrier 1914 \u00e0 Saint-Moreil ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_644\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-31758","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=31758"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31758\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=31758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=31758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=31758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}