{"id":31791,"date":"2019-07-29T22:09:59","date_gmt":"2019-07-29T20:09:59","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=31791"},"modified":"2020-09-21T16:42:58","modified_gmt":"2020-09-21T14:42:58","slug":"b_680","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_680\/","title":{"rendered":"BONNET Eug\u00e8ne Auguste (1884-1913)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 02\/09\/2026<\/p><h2 style=\"text-align: center;\"><strong>Eug\u00e8ne Auguste BONNET<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>Eug\u00e8ne BONNET<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>1884 &#8211; 1913<\/strong><\/p>\n<h4 style=\"text-align: center;\"><strong><span style=\"color: #008000;\">pl\u00e2trier<\/span> <\/strong>puis<span style=\"color: #008000;\"><strong> gar\u00e7on brasseur<\/strong><\/span><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">n\u00e9 au bourg de Roy\u00e8re<\/p>\n<p style=\"text-align: center;\">le 3 septembre 1884<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">L\u00e9onard BONNET, <span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">Marie BEAUVAIS, cultivatrice<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1905<\/strong><em>, Eug\u00e8ne, <\/em><span style=\"color: #008000;\"><strong>pl\u00e2trier<\/strong><\/span><em>, se pr\u00e9sente au conseil de r\u00e9vision avec une <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/\/wp-content\/uploads\/LEXIQUE\/HERNIE_INGUINALE.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\u25ba<\/a><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/08\/HERNIE-INGUINALE.png\" target=\"_blank\" rel=\"noopener noreferrer\">hernie inguinale<\/a><\/span> volumineuse.<\/em><\/p>\n<p><strong>En 1906<\/strong><em>, il travaille \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Paris (75)<\/strong><\/span><em> et loge 50, rue du Ruisseau dans le 18e\u00a0arrondissement.<\/em><\/p>\n<p><em>Il \u00e9pouse Blanche L\u00e9ontine <\/em><strong>RIB\u00c9MONT<\/strong><em> le 20 octobre de la m\u00eame ann\u00e9e \u00e0 Paris 16e. <\/em><\/p>\n<p><strong>En 1908<\/strong><em>, ils habitent 19, rue de Passy dans le 16e\u00a0;<\/em><\/p>\n<p><strong>de 1910 \u00e0 1913<\/strong><em>, 118, rue Marcadet dans le 18e. <\/em><\/p>\n<p><em>Eug\u00e8ne, <\/em><span style=\"color: #008000;\"><strong>gar\u00e7on brasseur<\/strong><\/span><em>, d\u00e9c\u00e8de \u00e0 cette adresse, le 9 janvier <\/em><strong>1913<\/strong><em>, \u00e2g\u00e9 de 28 ans.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 02\/09\/2026Eug\u00e8ne Auguste BONNET Eug\u00e8ne BONNET 1884 &#8211; 1913 pl\u00e2trier puis gar\u00e7on brasseur &nbsp; n\u00e9 au bourg de Roy\u00e8re le 3 septembre 1884 fils de L\u00e9onard BONNET, ma\u00e7on Marie BEAUVAIS, cultivatrice \u25d9 En 1905, Eug\u00e8ne, pl\u00e2trier, se pr\u00e9sente au conseil de r\u00e9vision avec une \u25bahernie inguinale volumineuse. En 1906, il travaille ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_680\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-31791","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=31791"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31791\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=31791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=31791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=31791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}