{"id":31920,"date":"2019-07-29T22:09:56","date_gmt":"2019-07-29T20:09:56","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=31920"},"modified":"2020-01-20T11:11:08","modified_gmt":"2020-01-20T10:11:08","slug":"b_667","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_667\/","title":{"rendered":"BONNAVAUD L\u00e9onard (1849\u2013apr\u00e8s 1870)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 02\/09\/2026<\/p><h2 style=\"text-align: center;\"><strong>L\u00e9onard BONNAVAUD<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1849 \u2013 apr\u00e8s 1870<\/strong><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Labassat (Saint-Junien-la-Breg\u00e8re)<\/p>\n<p style=\"text-align: center;\">le 5 mai 1849<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Guillaume BONNAVAUD, <strong><span style=\"color: #008000;\">ma\u00e7on<\/span> <\/strong>et meunier<\/p>\n<p style=\"text-align: center;\">Jeanne CHAMPEYMOND, cultivatrice<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1870<\/strong><em>, L\u00e9onard est exempt\u00e9 de service militaire comme fils a\u00een\u00e9 de veuve.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 02\/09\/2026L\u00e9onard BONNAVAUD 1849 \u2013 apr\u00e8s 1870 ma\u00e7on n\u00e9 \u00e0 Labassat (Saint-Junien-la-Breg\u00e8re) le 5 mai 1849 fils de Guillaume BONNAVAUD, ma\u00e7on et meunier Jeanne CHAMPEYMOND, cultivatrice \u25d9 En 1870, L\u00e9onard est exempt\u00e9 de service militaire comme fils a\u00een\u00e9..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_667\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-31920","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=31920"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/31920\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=31920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=31920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=31920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}