{"id":32082,"date":"2019-07-29T22:09:50","date_gmt":"2019-07-29T20:09:50","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=32082"},"modified":"2020-10-09T09:06:28","modified_gmt":"2020-10-09T07:06:28","slug":"b_659","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_659\/","title":{"rendered":"BONNAVAUD Antoine (1842\u20131911)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 02\/09\/2026<\/p><h2 style=\"text-align: center;\"><strong>Antoine BONNAVAUD<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1842 \u2013 1911<\/strong><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-7772.jpg\" alt=\"\" data-asset-id=\"32081\" data-source-id=\"i.0\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on <\/strong><\/span>et<strong>\u00a0\u25ba<a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/08\/FERMIER-M\u00c9TAYER.png\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #008000;\">fermier<\/span><\/a><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 La Villatte (Saint-Junien-la-Breg\u00e8re)<\/p>\n<p style=\"text-align: center;\">le 18 juillet 1842<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Pierre BONNAVAUD \/ Magdeleine CHARBONNIER<\/p>\n<p style=\"text-align: center;\">propri\u00e9taires cultivateurs<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1863<\/strong><em>, Antoine se pr\u00e9sente devant le conseil de r\u00e9vision avec des varices aux jambes.<\/em><\/p>\n<p><em>Il \u00e9pouse Antoinette <\/em><strong>GRANDRIEUX<\/strong><em> le 11 mars <\/em><strong>1869<\/strong><em> \u00e0 Roy\u00e8re (contrat Toumieux).<\/em> <em>Ils habitent Lachaud-Couraud, commune de Gentioux, puis le bourg de Roy\u00e8re.<\/em><\/p>\n<p><em>Ils d\u00e9c\u00e8dent \u00e0 Roy\u00e8re\u00a0:<\/em><\/p>\n<ul>\n<li><em>Antoine, le 8 juillet <\/em><strong>1911<\/strong><em>, \u00e2g\u00e9 de 68 ans<\/em><\/li>\n<li><em>Antoinette, le 12 avril <\/em><strong>1934<\/strong><em>, \u00e2g\u00e9e de 85 ans<\/em><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 02\/09\/2026Antoine BONNAVAUD 1842 \u2013 1911 ma\u00e7on et\u00a0\u25bafermier &nbsp; n\u00e9 \u00e0 La Villatte (Saint-Junien-la-Breg\u00e8re) le 18 juillet 1842 fils de Pierre BONNAVAUD \/ Magdeleine CHARBONNIER propri\u00e9taires cultivateurs \u25d9 En 1863, Antoine se pr\u00e9sente devant le conseil de r\u00e9vision avec des varices aux jambes. Il \u00e9pouse Antoinette GRANDRIEUX le 11 mars 1869 ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_659\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-32082","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=32082"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32082\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=32082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=32082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=32082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}