{"id":32084,"date":"2019-07-29T22:09:50","date_gmt":"2019-07-29T20:09:50","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=32084"},"modified":"2020-01-20T11:11:12","modified_gmt":"2020-01-20T10:11:12","slug":"b_692","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_692\/","title":{"rendered":"BONNET L\u00e9onard (1826-apr\u00e8s 1862)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 02\/09\/2026<\/p><h2 style=\"text-align: center;\"><strong>L\u00e9onard BONNET<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1826 &#8211; apr\u00e8s 1862<\/strong><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-7773.jpg\" alt=\"\" data-asset-id=\"32083\" data-source-id=\"i.0\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Neuvialle (Saint-Martin-Ch\u00e2teau)<\/p>\n<p style=\"text-align: center;\">le 30 octobre 1826<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Jean BONNET \/ Fran\u00e7oise PINGOUX<\/p>\n<p style=\"text-align: center;\">laboureurs<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><em>L\u00e9onard \u00e9pouse Marie <\/em><strong>JEANNETAUD<\/strong><em>.<\/em><\/p>\n<p><strong>En 1862<\/strong>, <em>veuf,<\/em> <em>il travaille \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Bordeaux (33)<\/strong><\/span><em>, et loge 16, rue Julie.<\/em><\/p>\n<p><em>Le 16 d\u00e9cembre de la m\u00eame ann\u00e9e, il s\u2019y remarie avec Jeanne <\/em><strong>CHEMINADE<\/strong><em>, ouvri\u00e8re aux tabacs native de Corr\u00e8ze (mari\u00e9s sans contrat).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 02\/09\/2026L\u00e9onard BONNET 1826 &#8211; apr\u00e8s 1862 ma\u00e7on n\u00e9 \u00e0 Neuvialle (Saint-Martin-Ch\u00e2teau) le 30 octobre 1826 fils de Jean BONNET \/ Fran\u00e7oise PINGOUX laboureurs \u25d9 L\u00e9onard \u00e9pouse Marie JEANNETAUD. En 1862, veuf, il travaille \u00e0 Bordeaux (33), et loge 16, rue Julie. Le 16 d\u00e9cembre de la m\u00eame ann\u00e9e, il s\u2019y ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_692\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-32084","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=32084"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32084\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=32084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=32084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=32084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}