{"id":32119,"date":"2019-07-29T22:09:46","date_gmt":"2019-07-29T20:09:46","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=32119"},"modified":"2022-03-07T16:29:48","modified_gmt":"2022-03-07T15:29:48","slug":"b_635","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_635\/","title":{"rendered":"BLANCHON Joseph (1841\u20131894)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 02\/09\/2026<\/p><h2 style=\"text-align: center;\"><strong>Joseph BLANCHON<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1841 \u2013 1894<\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-7788.jpg\" alt=\"\" width=\"322\" height=\"131\" data-asset-id=\"32118\" data-source-id=\"i.0\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span> et\u00a0<em><strong>\u25ba<a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/08\/LOGEUR-LOGEUSE.png\"><span style=\"color: #008000;\">logeur<\/span><\/a><\/strong><\/em><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">n\u00e9 au bourg du Monteil-au-Vicomte<\/p>\n<p style=\"text-align: center;\">le 9 mai 1841<\/p>\n<p style=\"text-align: center;\">fils naturel de<\/p>\n<p style=\"text-align: center;\">Anne BLANCHON<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><em>Joseph, <\/em><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><em>, \u00e9pouse Marie Eug\u00e9nie <\/em><strong>VIOLON<\/strong><em> le 30 janvier <\/em><strong>1868<\/strong><em> au Monteil-au-Vicomte (contrat Gloumeau). <\/em><\/p>\n<p><strong>En 1879<\/strong><em>, ils habitent <\/em><span style=\"color: #0000ff;\"><strong>Paris (75)\u00a0<\/strong><\/span><em>;<\/em><\/p>\n<p><strong>en 1885<\/strong><em>, Joseph est <\/em><span style=\"color: #008000;\"><strong>logeur<\/strong><\/span><em>, 21, rue de Bi\u00e8vre, 5e arrondissement\u00a0;<\/em><\/p>\n<p><strong>en 1893<\/strong><em>, les \u00e9poux sont toujours \u00e0 Paris.<\/em><\/p>\n<p><em>Joseph d\u00e9c\u00e8de en leur domicile, au 2e arrondissement, le 8 avril <\/em><strong>1894<\/strong><em>, \u00e2g\u00e9 de 52 ans.<\/em><\/p>\n<p><strong>En 1902<\/strong><em>, Marie Eug\u00e9nie est concierge, et habite 14, rue de Lanneau, Paris 5e.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 02\/09\/2026Joseph BLANCHON 1841 \u2013 1894 ma\u00e7on et\u00a0\u25balogeur &nbsp; n\u00e9 au bourg du Monteil-au-Vicomte le 9 mai 1841 fils naturel de Anne BLANCHON \u25d9 Joseph, ma\u00e7on, \u00e9pouse Marie Eug\u00e9nie VIOLON le 30 janvier 1868 au Monteil-au-Vicomte (contrat Gloumeau). En 1879, ils habitent Paris (75)\u00a0; en 1885, Joseph est logeur, 21, rue ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_635\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-32119","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=32119"}],"version-history":[{"count":2,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32119\/revisions"}],"predecessor-version":[{"id":195701,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32119\/revisions\/195701"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=32119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=32119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=32119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}