{"id":32905,"date":"2019-07-29T22:16:49","date_gmt":"2019-07-29T20:16:49","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=32905"},"modified":"2020-10-13T14:06:22","modified_gmt":"2020-10-13T12:06:22","slug":"b_1072","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_1072\/","title":{"rendered":"BOURDEIX Paul Louis Fran\u00e7ois (1859\u20131906)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 01\/09\/2026<\/p><h2 style=\"text-align: center;\"><strong>Paul Louis Fran\u00e7ois BOURDEIX<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong> Paul BOURDEIX<\/strong><\/p>\n<p style=\"text-align: center;\"><strong> 1859 \u2013 1906<\/strong><\/p>\n<p style=\"text-align: center;\"><strong> <img decoding=\"async\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-7912.jpg\" alt=\"\" data-asset-id=\"32903\" data-source-id=\"i.0\" \/><\/strong><\/p>\n<h4 style=\"text-align: center;\"><strong><span style=\"color: #008000;\">\u25ba\u00a0<a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/07\/MA\u00ceTRE-MA\u00c7ON.png\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #008000;\">ma\u00eetre ma\u00e7on<\/span><\/a><\/span><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">n\u00e9 au bourg de Saint-Pardoux-Lavaud<\/p>\n<p style=\"text-align: center;\">le 3 mars 1859<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Jean BOURDEIX, instituteur \/ Fran\u00e7oise TRUFFY<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1883 et 1884<\/strong><em>, Paul travaille \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Lyon (69)<\/strong><\/span><em>, et loge 13, rue du Mail. <\/em><\/p>\n<p><em>Il \u00e9pouse \u00e0 Lyon 4e, le 28 ao\u00fbt <\/em><strong>1884<\/strong><em> Jeanne Marie <\/em><strong>GOUAT<\/strong><em>, couturi\u00e8re originaire de la Loire (contrat Rambaud \u00e0 Fontaines-sur-Sa\u00f4ne).<\/em><\/p>\n<p><strong>En 1895<\/strong><em>, il est \u00e0 <\/em><strong><span style=\"color: #0000ff;\">Oullins (69)<\/span>\u00a0<\/strong><em>; <\/em><\/p>\n<p><strong>en 1906<\/strong><em>, \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Villeurbanne (69)<\/strong><\/span><em> .<\/em><\/p>\n<p><em>Il d\u00e9c\u00e8de \u00e0 \u25ba<a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/\/wp-content\/uploads\/PHOTOS_-_CARTES_POSTALES\/LYON_-_Hopital_de_lHotel-Dieu.jpg\" target=\"_blank\" rel=\"noopener noreferrer\">l\u2019H\u00f4tel-Dieu<\/a> de Lyon le 12 janvier de la m\u00eame ann\u00e9e, \u00e2g\u00e9 de 46 ans.<\/em><\/p>\n<p><em>Sa veuve d\u00e9c\u00e8de en son domicile, 62, rue du Quatre-Ao\u00fbt, \u00e0 Villeurbanne, le 18 septembre <\/em>1924<em>, \u00e2g\u00e9e de 62 ans.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 01\/09\/2026Paul Louis Fran\u00e7ois BOURDEIX Paul BOURDEIX 1859 \u2013 1906 \u25ba\u00a0ma\u00eetre ma\u00e7on &nbsp; n\u00e9 au bourg de Saint-Pardoux-Lavaud le 3 mars 1859 fils de Jean BOURDEIX, instituteur \/ Fran\u00e7oise TRUFFY \u25d9 En 1883 et 1884, Paul travaille \u00e0 Lyon (69), et loge 13, rue du Mail. Il \u00e9pouse \u00e0 Lyon 4e, ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_1072\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-32905","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=32905"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32905\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=32905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=32905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=32905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}