{"id":32921,"date":"2019-07-29T22:16:48","date_gmt":"2019-07-29T20:16:48","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=32921"},"modified":"2020-01-20T11:10:55","modified_gmt":"2020-01-20T10:10:55","slug":"b_1067","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_1067\/","title":{"rendered":"BOURDEIX L\u00e9onard (1856\u20131936)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 01\/09\/2026<\/p><h2 style=\"text-align: center;\"><strong>L\u00e9onard BOURDEIX<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1856 \u2013 1936<\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-7917.jpg\" alt=\"\" width=\"274\" height=\"126\" data-asset-id=\"32917\" data-source-id=\"i.0\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on <\/strong><\/span>et<span style=\"color: #008000;\"><strong> cultivateur<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Pr\u00e9sench\u00e8re (Saint-Moreil)<\/p>\n<p style=\"text-align: center;\">le 4 juin 1856<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Fran\u00e7ois BOURDEIX, <span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">Th\u00e9r\u00e8se LINTIGNAT, cultivatrice<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><em>L\u00e9onard \u00e9pouse Anne <\/em><strong>VIALATOUX<\/strong><em> le 8 mars <\/em><strong>1891<\/strong><em> \u00e0 Peyrat-le-Ch\u00e2teau (87 \u2013 contrat Tramonteil).<\/em><\/p>\n<p><em> Ils habitent Pr\u00e9sench\u00e8re.<\/em><\/p>\n<p><em>Ils y d\u00e9c\u00e8dent\u00a0:<\/em><\/p>\n<ul>\n<li><em>Anne, le 24 octobre <\/em><strong>1908<\/strong><em>, \u00e2g\u00e9e de 42 ans<\/em><\/li>\n<li><em>L\u00e9onard, le 1er janvier <\/em><strong>1936<\/strong><em>, \u00e2g\u00e9 de 79 ans<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 01\/09\/2026L\u00e9onard BOURDEIX 1856 \u2013 1936 ma\u00e7on et cultivateur n\u00e9 \u00e0 Pr\u00e9sench\u00e8re (Saint-Moreil) le 4 juin 1856 fils de Fran\u00e7ois BOURDEIX, ma\u00e7on Th\u00e9r\u00e8se LINTIGNAT, cultivatrice \u25d9 L\u00e9onard \u00e9pouse Anne VIALATOUX le 8 mars 1891 \u00e0 Peyrat-le-Ch\u00e2teau (87 \u2013 contrat Tramonteil). Ils habitent Pr\u00e9sench\u00e8re. Ils y d\u00e9c\u00e8dent\u00a0: Anne, le 24 octobre 1908, ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_1067\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-32921","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=32921"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32921\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=32921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=32921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=32921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}