{"id":32965,"date":"2019-07-29T22:16:42","date_gmt":"2019-07-29T20:16:42","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=32965"},"modified":"2020-09-01T18:33:53","modified_gmt":"2020-09-01T16:33:53","slug":"b_1066","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_1066\/","title":{"rendered":"BOURDEIX L\u00e9onard (1855\u20131925)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 02\/09\/2026<\/p><h2 style=\"text-align: center;\"><strong>L\u00e9onard BOURDEIX<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1855 \u2013 1925<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/bourdeix-Le.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-177622\" src=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/bourdeix-Le-300x49.jpg\" alt=\"\" width=\"300\" height=\"49\" srcset=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/bourdeix-Le-300x49.jpg 300w, https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/bourdeix-Le-150x25.jpg 150w, https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2019\/07\/bourdeix-Le.jpg 671w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on <\/strong><\/span>et <span style=\"color: #008000;\"><strong>propri\u00e9taire cultivateur<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 La Cour-de-Rozet (Saint-Pardoux-Lavaud)<\/p>\n<p style=\"text-align: center;\">le 5 novembre 1855<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Joseph BOURDEIX, <strong><span style=\"color: #008000;\">ma\u00e7on<\/span> \/ <\/strong>Marie SIMONET<\/p>\n<p style=\"text-align: center;\">propri\u00e9taires cultivateurs<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><em>Au cours des ann\u00e9es, L\u00e9onard r\u00e9side\u00a0:<\/em><\/p>\n<p><em> \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Lyon (69)<\/strong><\/span><em>, 16, rue Villeroi, <\/em><\/p>\n<p><em>\u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Paris (75)<\/strong><\/span><em>, rue Galande, <\/em><\/p>\n<p><em>puis \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Heyrieux (38)<\/strong><\/span><em>, <\/em><\/p>\n<p><em>\u00e0 Lyon, 185, rue de la Demi-Lune, ensuite 72, rue de la Part-Dieu.<\/em><\/p>\n<p><em> Il \u00e9pouse Marie <\/em><strong>VASSIVI\u00c8RE<\/strong><em> le 12 f\u00e9vrier <\/em><strong>1887<\/strong><em> \u00e0 Saint-Pardoux\u00a0 (contrat Magadoux \u00e0 Saint-Martin-Ch\u00e2teau). Ils habitent La Vedrenne, commune de Saint-Pardoux.<\/em><\/p>\n<p><strong>En 1888<\/strong><em>, L\u00e9onard d\u00e9pend du bureau de recrutement de la <\/em><span style=\"color: #0000ff;\"><strong>Seine<\/strong><\/span><em>\u00a0;<\/em><\/p>\n<p><strong>en 1896<\/strong><em>, il travaille \u00e0 Lyon et loge 261, rue de Cr\u00e9qui. <\/em><\/p>\n<p><em>Les \u00e9poux d\u00e9c\u00e8dent \u00e0 Lavaud, commune de Saint-Pardoux\u00a0:<\/em><\/p>\n<ul>\n<li><em>L\u00e9onard, le 3 novembre <\/em><strong>1925<\/strong><em>, \u00e2g\u00e9 de 69 ans<\/em><\/li>\n<li><em>Marie, le 12 novembre de la m\u00eame ann\u00e9e, \u00e2g\u00e9e de 63 ans<\/em><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 02\/09\/2026L\u00e9onard BOURDEIX 1855 \u2013 1925 &nbsp; ma\u00e7on et propri\u00e9taire cultivateur n\u00e9 \u00e0 La Cour-de-Rozet (Saint-Pardoux-Lavaud) le 5 novembre 1855 fils de Joseph BOURDEIX, ma\u00e7on \/ Marie SIMONET propri\u00e9taires cultivateurs \u25d9 Au cours des ann\u00e9es, L\u00e9onard r\u00e9side\u00a0: \u00e0 Lyon (69), 16, rue Villeroi, \u00e0 Paris (75), rue Galande, puis \u00e0 Heyrieux ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_1066\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-32965","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=32965"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/32965\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=32965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=32965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=32965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}