{"id":3943,"date":"2019-07-22T21:34:07","date_gmt":"2019-07-22T19:34:07","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=3943"},"modified":"2022-06-08T17:04:29","modified_gmt":"2022-06-08T15:04:29","slug":"v_21","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-v\/v_21\/","title":{"rendered":"VAREILLAUD Antoine (1835\u2013apr\u00e8s 1867)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>Antoine VAREILLAUD<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1835 \u2013 apr\u00e8s 1867<\/strong><\/p>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/07\/ne-sait-pas-signer.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-174596 aligncenter\" src=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/07\/ne-sait-pas-signer.jpg\" alt=\"\" width=\"156\" height=\"31\" srcset=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/07\/ne-sait-pas-signer.jpg 156w, https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/07\/ne-sait-pas-signer-150x30.jpg 150w\" sizes=\"auto, (max-width: 156px) 100vw, 156px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Vauveix (Roy\u00e8re)<\/p>\n<p style=\"text-align: center;\">le 18 mai 1835<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Cl\u00e9ment VAREILLAUD \/ Marie ANDRIEUX<\/p>\n<p style=\"text-align: center;\">propri\u00e9taires cultivateurs<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1860<\/strong><em>, Antoine travaille \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Bordeaux (33)<\/strong><\/span><em>, et loge 36, rue Beaufleury, puis 16, rue Citron.<\/em><\/p>\n<p><em>Le 23 f\u00e9vrier de la m\u00eame ann\u00e9e, il y \u00e9pouse Anne <\/em><strong>JOURDE<\/strong><em>, tailleuse en robes, native de Haute-Loire.<\/em><\/p>\n<p><strong>En 1867<\/strong><em>, ils sont \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Saint-Gen\u00e8s (33)<\/strong><\/span><em>.<\/em><\/p>\n<p><em>Anne d\u00e9c\u00e8de veuve chez son gendre \u00a0\u00e0 Paris 5<sup>e<\/sup>, \u00a0le 23 janvier <\/em><strong>1922<\/strong>,<em> \u00e2g\u00e9e de 86 ans.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026Antoine VAREILLAUD 1835 \u2013 apr\u00e8s 1867 ma\u00e7on n\u00e9 \u00e0 Vauveix (Roy\u00e8re) le 18 mai 1835 fils de Cl\u00e9ment VAREILLAUD \/ Marie ANDRIEUX propri\u00e9taires cultivateurs \u25d9 En 1860, Antoine travaille \u00e0 Bordeaux (33), et loge 36, rue Beaufleury, puis 16, rue Citron. Le 23 f\u00e9vrier de la m\u00eame ann\u00e9e, il y ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-v\/v_21\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3943","post","type-post","status-publish","format-standard","hentry","category-lettre-v"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/3943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=3943"}],"version-history":[{"count":3,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/3943\/revisions"}],"predecessor-version":[{"id":200307,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/3943\/revisions\/200307"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=3943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=3943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=3943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}