{"id":40110,"date":"2019-08-06T13:17:46","date_gmt":"2019-08-06T11:17:46","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=40110"},"modified":"2020-01-20T11:06:01","modified_gmt":"2020-01-20T10:06:01","slug":"b_0726a-bontemps-laurent","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_0726a-bontemps-laurent\/","title":{"rendered":"BONTEMPS Laurent (1839-1889)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 01\/09\/2026<\/p>\r\n<h2 style=\"text-align: center;\"><strong>Laurent BONTEMPS<\/strong><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\"><strong>1839 \u2013 1889<\/strong><\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-image\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image2-238.jpg\" alt=\"\" \/><\/h4>\r\n\r\n\r\n\r\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on <\/strong><\/span>et<span style=\"color: #008000;\"><strong> cultivateur<\/strong><\/span><\/h4>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">n\u00e9 au moulin de Labassat (Saint-Junien-la-Breg\u00e8re)<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">le 17 novembre 1839<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">fils de<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">Pierre BONTEMPS \/ Antoinette BONNAVAUD<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">meuniers<\/p>\r\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>En 1860<\/strong><em>, Laurent est exempt\u00e9 de service militaire comme fils a\u00een\u00e9 de veuve.<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Il \u00e9pouse Marie <\/em><strong>JAMMOT<\/strong><em> le 12 f\u00e9vrier <\/em><strong>1862<\/strong><em> \u00e0 Saint-Junien (contrat Berger \u00e0 Bourganeuf). Ils habitent Le Puy, commune de Saint-Junien.<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Marie y d\u00e9c\u00e8de le 9 f\u00e9vrier <\/em><strong>1877<\/strong><em>, \u00e2g\u00e9e de 38 ans. <\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Laurent se remarie avec Marie <\/em><strong>BONNAVAUD<\/strong><em>, couturi\u00e8re, le 28 octobre <\/em><strong>1880<\/strong><em> \u00e0 Saint-Junien-la-Breg\u00e8re (mari\u00e9s sans contrat). <\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Il d\u00e9c\u00e8de au Puy le 1er mars <\/em><strong>1889<\/strong><em>, \u00e2g\u00e9 de 49 ans. <\/em><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 01\/09\/2026 Laurent BONTEMPS 1839 \u2013 1889 ma\u00e7on et cultivateur n\u00e9 au moulin de Labassat (Saint-Junien-la-Breg\u00e8re) le 17 novembre 1839 fils de Pierre BONTEMPS \/ Antoinette BONNAVAUD meuniers \u25d9 En 1860, Laurent est exempt\u00e9 de service militaire comme fils a\u00een\u00e9 de veuve. Il \u00e9pouse Marie JAMMOT le 12 f\u00e9vrier 1862 \u00e0 ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_0726a-bontemps-laurent\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-40110","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/40110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=40110"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/40110\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=40110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=40110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=40110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}