{"id":40261,"date":"2019-08-07T08:41:10","date_gmt":"2019-08-07T06:41:10","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=40261"},"modified":"2020-10-03T17:15:28","modified_gmt":"2020-10-03T15:15:28","slug":"b_0614b-biolette-francois","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_0614b-biolette-francois\/","title":{"rendered":"BIOLETTE Fran\u00e7ois (1872-1928)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 01\/09\/2026<\/p>\r\n<h2 style=\"text-align: center;\"><strong>Fran\u00e7ois BIOLETTE<\/strong><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\"><strong>1872 \u2013 1928<\/strong><\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image2-241.jpg\" alt=\"\" \/><\/figure>\r\n\r\n\r\n\r\n<h4 style=\"text-align: center;\"><strong>\u25ba<\/strong><strong><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/07\/FUMISTE.png\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #008000;\">fumiste<\/span><\/a><\/strong>\u00a0<span style=\"color: #000000;\">et<\/span>\u00a0<span style=\"color: #008000;\"><strong>propri\u00e9taire cultivateur<\/strong><\/span><\/h4>\r\n\r\n\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Auzoux (Roy\u00e8re)<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">le 2 septembre 1872<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">fils de<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">Antoine BIOLETTE, <span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">Antoinette CHENAUD, cultivatrice<\/p>\r\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>En 1896<\/strong><em>, Fran\u00e7ois travaille \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Bordeaux (33)<\/strong><\/span><em>, et loge 13, rue Monsarrat\u00a0; <\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>en 1899<\/strong><em>, \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Frontignan (34)<\/strong><em>.<\/em><\/span><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em> Il \u00e9pouse Marie-Louise <\/em><strong>BOUCAUD<\/strong><em> le 24 f\u00e9vrier <\/em><strong>1900<\/strong> <em>\u00e0 Roy\u00e8re (contrat Toumieux). Ils habitent Auzoux. <\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>En mars de la m\u00eame ann\u00e9e, Fran\u00e7ois est \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Lorette (42)<\/strong><\/span><em>\u00a0;<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>puis \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Lyon (69)<\/strong><\/span><em>\u00a0:<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>en 1901 et 1902<\/strong><em>, 36, cours Vitton\u00a0;<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>en 1903, 1909 et 1913<\/strong><em>, 45, grande rue Croix-Rousse. <\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Les \u00e9poux d\u00e9c\u00e8dent \u00e0 Auzoux\u00a0:<\/em><\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><em>Fran\u00e7ois, le 21 d\u00e9cembre <\/em><strong>1928<\/strong><em>, \u00e2g\u00e9 de 56 ans<\/em><\/li>\r\n<li><em>Marie-Louise, le 3 ao\u00fbt <\/em><strong>1957<\/strong><em>, \u00e2g\u00e9e de 76 ans<\/em><\/li>\r\n<\/ul>\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 01\/09\/2026 Fran\u00e7ois BIOLETTE 1872 \u2013 1928 \u25bafumiste\u00a0et\u00a0propri\u00e9taire cultivateur &nbsp; n\u00e9 \u00e0 Auzoux (Roy\u00e8re) le 2 septembre 1872 fils de Antoine BIOLETTE, ma\u00e7on Antoinette CHENAUD, cultivatrice \u25d9 En 1896, Fran\u00e7ois travaille \u00e0 Bordeaux (33), et loge 13, rue Monsarrat\u00a0; en 1899, \u00e0 Frontignan (34). Il \u00e9pouse Marie-Louise BOUCAUD le 24 f\u00e9vrier ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_0614b-biolette-francois\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-40261","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/40261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=40261"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/40261\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=40261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=40261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=40261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}