{"id":40974,"date":"2019-08-10T16:46:58","date_gmt":"2019-08-10T14:46:58","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=40974"},"modified":"2020-01-20T11:05:59","modified_gmt":"2020-01-20T10:05:59","slug":"b_0461a-bertrand-francois","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_0461a-bertrand-francois\/","title":{"rendered":"BERTRAND Fran\u00e7ois (1851\u2013apr\u00e8s 1872)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 01\/09\/2026<\/p>\r\n<h2 style=\"text-align: center;\"><strong>Fran\u00e7ois BERTRAND<\/strong><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\"><strong>Fran\u00e7ois Auguste BERTRAND<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\"><strong>1851 \u2013 apr\u00e8s 1872<\/strong><\/p>\r\n\r\n\r\n\r\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/h4>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">n\u00e9 \u00e0 Guimont (Nedde \u2013 87)<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">le 14 novembre 1851<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">fils de<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">Jean BERTRAND, <span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: center;\">Marie LACOUR, cultivatrice<\/p>\r\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>En 1872<\/strong><em>, Fran\u00e7ois habite Vauveix, commune de Roy\u00e8re avec son p\u00e8re. Il est exempt\u00e9 de service militaire pour d\u00e9faut de taille (1m45).<\/em><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 01\/09\/2026 Fran\u00e7ois BERTRAND Fran\u00e7ois Auguste BERTRAND 1851 \u2013 apr\u00e8s 1872 ma\u00e7on n\u00e9 \u00e0 Guimont (Nedde \u2013 87) le 14 novembre 1851 fils de Jean BERTRAND, ma\u00e7on Marie LACOUR, cultivatrice \u25d9 En 1872, Fran\u00e7ois habite Vauveix, commune de Roy\u00e8re avec son p\u00e8re. Il est exempt\u00e9 de service militaire pour d\u00e9faut de ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-b\/b_0461a-bertrand-francois\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-40974","post","type-post","status-publish","format-standard","hentry","category-lettre-b"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/40974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=40974"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/40974\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=40974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=40974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=40974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}