{"id":5522,"date":"2019-07-28T13:46:55","date_gmt":"2019-07-28T11:46:55","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=5522"},"modified":"2022-04-06T13:42:10","modified_gmt":"2022-04-06T11:42:10","slug":"l_117","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_117\/","title":{"rendered":"LAGRANGE Antoine (1791-1879)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>Antoine LAGRANGE<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1791 \u2013 1879<\/strong><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Larfouill\u00e8re (Ch\u00e2tain)<\/p>\n<p style=\"text-align: center;\">le 17 mars 1791<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">L\u00e9onard LAGRANGE, <span style=\"color: #008000;\"><strong>ma\u00e7on <span style=\"color: #000000;\">\/ <\/span><\/strong><\/span>Marie SAUVANAUD<\/p>\n<p style=\"text-align: center;\">laboureurs<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1819<\/strong><em>, Antoine travaille \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Paris (75)<\/strong><\/span><em>.<\/em><\/p>\n<p><em>Il s\u2019y marie le 29 juin de la m\u00eame ann\u00e9e, en \u25ba<a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/\/wp-content\/uploads\/PHOTOS_-_CARTES_POSTALES\/PARIS_-_Eglise_Saint-Eustache.jpg\" target=\"_blank\" rel=\"noopener\">l\u2019\u00e9glise Saint-Eustache<\/a>, avec Marie Victoire <\/em><strong>GUILLAUMOT<\/strong><em>.<\/em><\/p>\n<p><em>Veuf, il se remarie avec Ad\u00e8le<\/em><strong> LAGARDE<\/strong><\/p>\n<p><strong>\u00a0En 1829<\/strong><em>, ils habitent 20, rue Pav\u00e9 Saint-Sauveur.<\/em><\/p>\n<p><em>\u00a0<\/em><em>Il d\u00e9c\u00e8de rentier, le 18 d\u00e9cembre <\/em><strong>1879<\/strong><em>, en son domicile, 7, rue Lesdigui\u00e8res, \u00e2g\u00e9 de 88 ans<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026Antoine LAGRANGE 1791 \u2013 1879 ma\u00e7on n\u00e9 \u00e0 Larfouill\u00e8re (Ch\u00e2tain) le 17 mars 1791 fils de L\u00e9onard LAGRANGE, ma\u00e7on \/ Marie SAUVANAUD laboureurs \u25d9 En 1819, Antoine travaille \u00e0 Paris (75). Il s\u2019y marie le 29 juin de la m\u00eame ann\u00e9e, en \u25bal\u2019\u00e9glise Saint-Eustache, avec Marie Victoire GUILLAUMOT. Veuf, il ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_117\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-5522","post","type-post","status-publish","format-standard","hentry","category-lettre-l"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=5522"}],"version-history":[{"count":2,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5522\/revisions"}],"predecessor-version":[{"id":197147,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5522\/revisions\/197147"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=5522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=5522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=5522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}