{"id":5571,"date":"2019-07-28T13:44:33","date_gmt":"2019-07-28T11:44:33","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=5571"},"modified":"2020-10-02T17:05:35","modified_gmt":"2020-10-02T15:05:35","slug":"l_106","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_106\/","title":{"rendered":"LAGAYE L\u00e9onard (1828-1860)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>L\u00e9onard LAGAYE<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1828 \u2013 1860<\/strong><\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-1234.jpg\" alt=\"\" data-source-id=\"i.0\" data-asset-id=\"5567\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on <\/strong>et<strong> <em>\u25ba<span style=\"color: #008000;\"><a style=\"color: #008000;\" href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-content\/uploads\/2020\/08\/LOGEUR-LOGEUSE.png\">logeur<\/a><\/span><\/em><br \/>\n<\/strong><\/span><\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">n\u00e9 aux Jarrauds (Saint-Martin-Ch\u00e2teau)<\/p>\n<p style=\"text-align: center;\">le 11 septembre 1828<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Jean LAGAYE,<span style=\"color: #008000;\"><strong> ma\u00e7on <\/strong><\/span><strong>\/ <\/strong>L\u00e9onarde JARRAUD<\/p>\n<p style=\"text-align: center;\">propri\u00e9taires cultivateurs<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><em>L\u00e9onard, <\/em><strong><span style=\"color: #008000;\">ma\u00e7on<\/span>,<\/strong><em> \u00e9pouse Marie-Anne <\/em><strong>CHAMPEAUX<\/strong><em> le 4 f\u00e9vrier <\/em><strong>1850<\/strong><em> \u00e0 Saint-Martin-Ch\u00e2teau (contrat JB Junien Faure)\u00a0; il ne sait pas encore signer. Ils vivent d\u2019abord \u00e0 La Seauve, commune de Saint-Martin.<\/em><\/p>\n<p><strong>En 1857 et 1858<\/strong><em>, ils sont <\/em><span style=\"color: #008000;\"><strong>logeurs<\/strong><\/span><em> \u00e0 <\/em><span style=\"color: #0000ff;\"><strong>Lyon (69)<\/strong><\/span><em>, 26, rue Madame. <\/em><\/p>\n<p><em>L\u00e9onard d\u00e9c\u00e8de \u00e0 La Seauve<\/em> <em>le 5 juin <\/em><strong>1860<\/strong><em>, \u00e2g\u00e9 de 31 ans. <\/em><\/p>\n<p><em>En 1862, sa veuve est toujours \u00e0 Lyon, 72, rue Moncey. Elle se remarie avec Pierre BOUDOT, ma\u00e7on, et d\u00e9c\u00e8de \u00e0 Saint-Martin le 9 mars 1870, \u00e2g\u00e9e de 38 ans.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026L\u00e9onard LAGAYE 1828 \u2013 1860 ma\u00e7on et \u25balogeur &nbsp; n\u00e9 aux Jarrauds (Saint-Martin-Ch\u00e2teau) le 11 septembre 1828 fils de Jean LAGAYE, ma\u00e7on \/ L\u00e9onarde JARRAUD propri\u00e9taires cultivateurs \u25d9 L\u00e9onard, ma\u00e7on, \u00e9pouse Marie-Anne CHAMPEAUX le 4 f\u00e9vrier 1850 \u00e0 Saint-Martin-Ch\u00e2teau (contrat JB Junien Faure)\u00a0; il ne sait pas encore signer. Ils ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_106\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-5571","post","type-post","status-publish","format-standard","hentry","category-lettre-l"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=5571"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5571\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=5571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=5571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=5571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}