{"id":5590,"date":"2019-07-28T13:44:31","date_gmt":"2019-07-28T11:44:31","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=5590"},"modified":"2020-01-20T11:25:54","modified_gmt":"2020-01-20T10:25:54","slug":"l_244","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_244\/","title":{"rendered":"LALEMODE L\u00e9onard (1820-1895)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>L\u00e9onard LALEMODE<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1820 \u2013 1895<\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-74.png\" alt=\"\" width=\"256\" height=\"77\" data-source-id=\"i.0\" data-asset-id=\"5588\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on <\/strong>et<strong> cultivateur<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Vige (Saint-Junien-la-Breg\u00e8re)<\/p>\n<p style=\"text-align: center;\">le 12 novembre 1820<\/p>\n<p style=\"text-align: center;\">fils de<\/p>\n<p style=\"text-align: center;\">Michel LALEMODE,<span style=\"color: #008000;\"><strong> ma\u00e7on<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">Fran\u00e7oise CHAUSSADE, cultivatrice<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><strong>En 1841<\/strong><em>, L\u00e9onard se pr\u00e9sente au conseil de r\u00e9vision avec une blessure \u00e0 la cuisse droite.<\/em><\/p>\n<p><em>Il \u00e9pouse Louise <\/em><strong>MEAUME<\/strong><em> le 13 mars <\/em><strong>1855<\/strong><em> \u00e0 Valli\u00e8re (contrat Vigier). Ils habitent d\u2019abord Vige.<\/em><\/p>\n<p><em> Ils d\u00e9c\u00e8dent \u00e0 Grandjanon, commune de Saint-Pierre-le-Bost\u00a0:<\/em><\/p>\n<p><em>\u2022\u00a0 L\u00e9onard, le 30 avril <\/em><strong>1895<\/strong><em>, \u00e2g\u00e9 de 74 ans<\/em><\/p>\n<p><em>\u2022\u00a0 Louise, le 13 f\u00e9vrier <\/em><strong>1912<\/strong><em>, \u00e2g\u00e9e de 79 ans<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026L\u00e9onard LALEMODE 1820 \u2013 1895 ma\u00e7on et cultivateur n\u00e9 \u00e0 Vige (Saint-Junien-la-Breg\u00e8re) le 12 novembre 1820 fils de Michel LALEMODE, ma\u00e7on Fran\u00e7oise CHAUSSADE, cultivatrice \u25d9 En 1841, L\u00e9onard se pr\u00e9sente au conseil de r\u00e9vision avec une blessure \u00e0 la cuisse droite. Il \u00e9pouse Louise MEAUME le 13 mars 1855 \u00e0 ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_244\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-5590","post","type-post","status-publish","format-standard","hentry","category-lettre-l"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=5590"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5590\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=5590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=5590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=5590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}