{"id":5606,"date":"2019-07-28T13:44:29","date_gmt":"2019-07-28T11:44:29","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=5606"},"modified":"2020-01-20T11:25:56","modified_gmt":"2020-01-20T10:25:56","slug":"l_259","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_259\/","title":{"rendered":"LAMOULINE Jean (d\u00e9c\u00e9d\u00e9 apr\u00e8s 1882)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>Jean LAMOULINE<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>d\u00e9c\u00e9d\u00e9 apr\u00e8s 1882<\/strong><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">de Saint-Martin-Ch\u00e2teau<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><em>Jean \u00e9pouse Marie <\/em><strong>COULAUD<\/strong><em>. <\/em><\/p>\n<p><strong>En 1882<\/strong><em>, il travaille \u00e0 <\/em><strong><span style=\"color: #0000ff;\">Paris (75<\/span>)<\/strong><em>, et loge 21, avenue de Saint-Ouen.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026Jean LAMOULINE d\u00e9c\u00e9d\u00e9 apr\u00e8s 1882 ma\u00e7on de Saint-Martin-Ch\u00e2teau \u25d9 Jean \u00e9pouse Marie COULAUD. En 1882, il travaille \u00e0 Paris (75), et loge 21, avenue de S..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_259\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-5606","post","type-post","status-publish","format-standard","hentry","category-lettre-l"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=5606"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5606\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=5606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=5606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=5606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}