{"id":5612,"date":"2019-07-28T13:44:29","date_gmt":"2019-07-28T11:44:29","guid":{"rendered":"http:\/\/lesmaconsdelacreuse.fr\/annuaire\/?p=5612"},"modified":"2020-01-20T11:25:56","modified_gmt":"2020-01-20T10:25:56","slug":"l_224","status":"publish","type":"post","link":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_224\/","title":{"rendered":"LALET L\u00e9onard (1802-1849)"},"content":{"rendered":"<p class=\"last-updated\"><strong>Mis \u00e0 jour le :<\/strong> 15\/07\/2026<\/p><h2 style=\"text-align: center;\"><strong>L\u00e9onard LALET<\/strong><\/h2>\n<p style=\"text-align: center;\"><strong>1802 \u2013 1849<\/strong><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" title=\"\" src=\"https:\/\/lesmaconsdelacreuse.fr\/annuaire\/wp-content\/uploads\/2019\/07\/image1-1249.jpg\" alt=\"\" data-source-id=\"i.0\" data-asset-id=\"5609\" \/><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>ma\u00e7on <\/strong>et <strong>propri\u00e9taire cultivateur<\/strong><\/span><\/h4>\n<p style=\"text-align: center;\">n\u00e9 \u00e0 Arpeix (Roy\u00e8re)<\/p>\n<p style=\"text-align: center;\">le 15 niv\u00f4se an X (5 janvier 1802)<\/p>\n<p style=\"text-align: center;\">Louis LALET, <span style=\"color: #008000;\"><strong>ma\u00e7on<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">Louise AUPHELLE, cultivatrice<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u25d9<\/span><\/p>\n<p><em>L\u00e9onard \u00e9pouse L\u00e9onarde <\/em><strong>PICARD<\/strong><em> le 14 f\u00e9vrier <\/em><strong>1828<\/strong><em> \u00e0 Roy\u00e8re (contrat Coutisson<\/em>).<\/p>\n<p><em>Ils habitent Arpeix.<\/em><\/p>\n<p><em> Ils y d\u00e9c\u00e8dent\u00a0:<\/em><\/p>\n<ul>\n<li><em>L\u00e9onard, le 13 f\u00e9vrier <\/em><strong>1849<\/strong><em>, \u00e2g\u00e9 de 47 ans (apr\u00e8s avoir test\u00e9 l\u2019ann\u00e9e pr\u00e9c\u00e9dente devant Me Toumieux de Roy\u00e8re)<\/em><\/li>\n<li><em>L\u00e9onarde, le 19 novembre de la m\u00eame ann\u00e9e, \u00e2g\u00e9e de 40 ans<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mis \u00e0 jour le : 15\/07\/2026L\u00e9onard LALET 1802 \u2013 1849 ma\u00e7on et propri\u00e9taire cultivateur n\u00e9 \u00e0 Arpeix (Roy\u00e8re) le 15 niv\u00f4se an X (5 janvier 1802) Louis LALET, ma\u00e7on Louise AUPHELLE, cultivatrice \u25d9 L\u00e9onard \u00e9pouse L\u00e9onarde PICARD le 14 f\u00e9vrier 1828 \u00e0 Roy\u00e8re (contrat Coutisson). Ils habitent Arpeix. Ils y d\u00e9c\u00e8dent\u00a0: L\u00e9onard, le 13 f\u00e9vrier ..<\/p>\n<div class=\"clear-fix\"><\/div>\n<p><a href=\"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/lettre-l\/l_224\/\" title=\"Lire la suite...\">Lire la suite<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-5612","post","type-post","status-publish","format-standard","hentry","category-lettre-l"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/comments?post=5612"}],"version-history":[{"count":0,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/posts\/5612\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/media?parent=5612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/categories?post=5612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmaconsdelacreuse.fr\/annuaires\/wp-json\/wp\/v2\/tags?post=5612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}